{"id":27433,"date":"2026-06-29T21:43:42","date_gmt":"2026-06-30T01:43:42","guid":{"rendered":"https:\/\/aleeknews.com\/4l33k5\/2026\/06\/29\/clientes-reclaman-la-restitucion-de-7-5-millones-en-depositos-en-nodus-bank-2\/"},"modified":"2026-06-29T21:43:42","modified_gmt":"2026-06-30T01:43:42","slug":"clientes-reclaman-la-restitucion-de-7-5-millones-en-depositos-en-nodus-bank-2","status":"publish","type":"post","link":"https:\/\/aleeknews.com\/4l33k5\/2026\/06\/29\/clientes-reclaman-la-restitucion-de-7-5-millones-en-depositos-en-nodus-bank-2\/","title":{"rendered":"Clientes reclaman la restituci\u00f3n de $7.5 millones en dep\u00f3sitos en Nodus Bank"},"content":{"rendered":"<div>\n<div data-testid=\"global-header-test\" data-fusion-lazy-id=\"f0f5G41E11Y61Ck\">\n<hr>\n<p><span>Bolsa de valores <b>01:43 AM<\/b><\/span><\/p>\n<\/div>\n<div>\n<div data-fusion-lazy-id=\"f0f9tfiOw0362nv\">\n<div class>\n<p><a href=\"https:\/\/thetrustproject.org\/\"><img decoding=\"async\" src=\"https:\/\/www.elnuevodia.com\/pf\/resources\/v2\/icons\/trust-icon.svg?d=230\"><\/a><\/p>\n<div>\n<p>Se adhiere a los criterios de The Trust Project<\/p>\n<\/div>\n<\/div>\n<div>\n<h2>La entidad financiera internacional, en proceso de liquidaci\u00f3n por la OCIF, habr\u00eda retenido sin justificaci\u00f3n el dinero de clientes, seg\u00fan dos pleitos ante el tribunal federal<\/h2>\n<div>\n<p>26 de septiembre de 2023 &#8211; 11:40 PM<\/p>\n<\/div>\n<div>\n<p><b>Archivo<\/b><\/p>\n<p>Esta historia fue publicada hace m\u00e1s de 2 a\u00f1os.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div data-fusion-lazy-id=\"f0f8wxHIPTYNet\">\n<div><picture><source media=\"(max-width: 375px)\" ><source media=\"(max-width: 767px)\" ><source media=\"(max-width: 1023px)\" ><source ><\/picture><figcaption>Al menos dos clientes de Nodus International Bank, una Entidad Financiera Internacional que operaba en Puerto Rico desde el 2009 y que ahora se encuentra en proceso de licitaci\u00f3n, recurrieron al tribunal federal para reclamar unos $7.5 millones en dep\u00f3sitos no restituidos. <span>(Archivo)<\/span><\/figcaption><\/div>\n<div>\n<p><img decoding=\"async\" alt=\"Efra\u00edn Montalb\u00e1n R\u00edos\" src=\"https:\/\/www.elnuevodia.com\/resizer\/v2\/https%3A%2F%2Fauthor-service-images-prod-us-east-1.publishing.aws.arc.pub%2Fgfrmedia%2Fb846106f-313f-4fa3-8690-8169fec53277.png?auth=b672eb01840f63d170a79ae205ccc29a2f694f1bb849b72693c84ad2cc16b7a1&#038;quality=75&#038;smart=true&#038;width=170&#038;height=147\"><\/p>\n<\/div>\n<div>\n<p>Cuatro meses despu\u00e9s de que Nodus International Bank Inc. aceptara suspender sus operaciones en Puerto Rico, al menos dos de sus clientes internacionales reclaman en el tribunal federal la restituci\u00f3n de unos $7.5 millones.<\/p>\n<\/div>\n<\/div>\n<section>\n<header><span>Popular en la Comunidad<\/span><\/header>\n<\/section>\n<\/div>\n<\/div>\n\n    <div class=\"xs_social_share_widget xs_share_url after_content \t\tmain_content  wslu-style-1 wslu-share-box-shaped wslu-fill-colored wslu-none wslu-share-horizontal wslu-theme-font-no wslu-main_content\">\n\n\t\t\n        <ul>\n\t\t\t        <\/ul>\n    <\/div> \n","protected":false},"excerpt":{"rendered":"<p>Bolsa de valores 01:43 AM Se adhiere a los criterios de The Trust Project La entidad financiera internacional, en proceso de liquidaci\u00f3n por la OCIF, habr\u00eda retenido sin justificaci\u00f3n el dinero de clientes, seg\u00fan dos pleitos ante el tribunal federal 26 de septiembre de 2023 &#8211; 11:40 PM Archivo Esta historia fue publicada hace m\u00e1s<\/p>\n","protected":false},"author":2,"featured_media":27428,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-27433","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/posts\/27433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/comments?post=27433"}],"version-history":[{"count":0,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/posts\/27433\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/media\/27428"}],"wp:attachment":[{"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/media?parent=27433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/categories?post=27433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/tags?post=27433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}