{"id":25018,"date":"2026-05-13T07:51:47","date_gmt":"2026-05-13T11:51:47","guid":{"rendered":"https:\/\/aleeknews.com\/4l33k5\/2026\/05\/13\/carnival-cruise-expandira-su-presencia-en-puerto-rico\/"},"modified":"2026-05-13T07:51:47","modified_gmt":"2026-05-13T11:51:47","slug":"carnival-cruise-expandira-su-presencia-en-puerto-rico","status":"publish","type":"post","link":"https:\/\/aleeknews.com\/4l33k5\/2026\/05\/13\/carnival-cruise-expandira-su-presencia-en-puerto-rico\/","title":{"rendered":"Carnival Cruise expandir\u00e1 su presencia en Puerto Rico"},"content":{"rendered":"<div>\n<p><b>Miami<\/b> &#8211; <b>Carnival Corporation<\/b> expandir\u00e1 su presencia en Puerto Rico, al confirmar que entre los a\u00f1os fiscales 2027 y 2028 contar\u00e1 con operaciones de sus marcas Carnival Cruise Line, Princess Cruises y Seabourn Cruise Line en los muelles de cruceros de San Juan.<\/p>\n<p>La directora ejecutiva de la <a href=\"https:\/\/www.elnuevodia.com\/topicos\/compa\u00f1ia-de-turismo-de-puerto-rico\" target=\"_self\" rel title=\"https:\/\/www.elnuevodia.com\/topicos\/compa\u00f1ia-de-turismo-de-puerto-rico\">Compa\u00f1\u00eda de Turismo de Puerto Rico<\/a> (CTPR), <b>Willianette Robles<\/b>, precis\u00f3 que las operaciones dejar\u00e1n un impacto econ\u00f3mico estimado en $32 millones.<\/p>\n<p><b>Del lado de Carnival Cruise Line, Robles detall\u00f3 que, en abril de 2027, arribar\u00e1 -por primera vez- a Puerto Rico, el Carnival Firenze<\/b><i><b>.<\/b><\/i><b> La \u00fanica visita de la embarcaci\u00f3n dejar\u00eda cerca de $400,000 en la econom\u00eda. <\/b><\/p>\n<p>Asimismo, la funcionaria inform\u00f3 que el crucero Carnival Festivale -cuyas salidas iniciar\u00e1n en 2027- tiene calendarizadas dos visitas al puerto de San Juan en junio del a\u00f1o pr\u00f3ximo, generando un impacto econ\u00f3mico que supera $1 mill\u00f3n para el a\u00f1o fiscal 2027.<\/p>\n<p>En entrevista con este diario, <b>Robles reconoci\u00f3 que Carnival Cruise Line todav\u00eda no tiene ning\u00fan barco en agenda para realizar operaciones de puerto base desde San Juan.<\/b><\/p>\n<p><h4><b>El verano de 2019<\/b><\/h4>\n<\/p>\n<p>La \u00faltima vez que Carnival oper\u00f3 salidas desde los muelles capitalinos fue en 2019.<\/p>\n<p>En reuniones con ejecutivos de Carnival, Robles dijo que la empresa tiene varias exigencias en t\u00e9rminos de infraestructura.<\/p>\n<p><b>\u201cCarnival, por lo que se va de Puerto Rico fue, lamentablemente, cuando vino el verano del 2019. La situaci\u00f3n y la experiencia que ellos sintieron con sus pasajeros de no sentirse seguros fue un problema y entonces, ellos fueron muy honestos\u201d<\/b>, sostuvo la funcionaria.<\/p>\n<p>Sin embargo, reclam\u00f3 que, a nivel corporativo, la empresa s\u00ed est\u00e1 apostando a Puerto Rico para operaciones de puerto base a trav\u00e9s de Princess Cruises, que retom\u00f3 sus operaciones en la isla en octubre de 2025.<\/p>\n<p><b>Robles inform\u00f3 que el crucero Crown Princess tendr\u00e1 operaciones de puerto base durante el a\u00f1o fiscal 2027. En total, la embarcaci\u00f3n operar\u00e1 14 viajes desde San Juan, con un impacto econ\u00f3mico de $13 millones.<\/b><\/p>\n<p>Mientras, el crucero Emerald Princess estar\u00e1 activo en el a\u00f1o fiscal 2028 realizando 18 paradas y generando $17.2 millones para la econom\u00eda local, seg\u00fan estimados de la CTPR.<\/p>\n<p><b>\u201cComenzamos recientemente con Princess y te tengo que decir que los comentarios han sido muy positivos. Ellos (<\/b><a href=\"https:\/\/www.elnuevodia.com\/topicos\/carnival-cruises\/\" target=\"_blank\" rel=\"noreferrer\" title=\"https:\/\/www.elnuevodia.com\/topicos\/carnival-cruises\/\"><b>Carnival<\/b><\/a><b>) est\u00e1n muy contentos con el trato de Princess\u201d<\/b>, reclam\u00f3.<\/p>\n<p><h4><b>Regresa Seabourn Cruise Line<\/b><\/h4>\n<\/p>\n<p>Robles agreg\u00f3 que Carnival Corporation tambi\u00e9n confirm\u00f3 el regreso a la isla de su marca de lujo Seabourn Cruise Line para el a\u00f1o fiscal 2027.<\/p>\n<p>Para ello, <b>la embarcaci\u00f3n Seabourn Ovation tiene en agenda una visita de puerto base y una parada en tr\u00e1nsito, que inyectar\u00eda cerca de $200,000.<\/b><\/p>\n<p>\u201cLa expansi\u00f3n de operaciones de Carnival Corporation en Puerto Rico reafirma la confianza de la industria de cruceros en nuestra isla como un destino competitivo dentro del Caribe. Este crecimiento impulsa la actividad econ\u00f3mica, fortalece nuestra oferta tur\u00edstica y genera oportunidades para nuestros comerciantes y proveedores locales\u201d, expres\u00f3 la gobernadora <a href=\"https:\/\/www.elnuevodia.com\/topicos\/jenniffer-gonzalez\" target=\"_self\" rel title=\"https:\/\/www.elnuevodia.com\/topicos\/jenniffer-gonzalez\">Jenniffer Gonz\u00e1lez Col\u00f3n<\/a>, en declaraciones escritas.<\/p>\n<\/div>\n\n    <div class=\"xs_social_share_widget xs_share_url after_content \t\tmain_content  wslu-style-1 wslu-share-box-shaped wslu-fill-colored wslu-none wslu-share-horizontal wslu-theme-font-no wslu-main_content\">\n\n\t\t\n        <ul>\n\t\t\t        <\/ul>\n    <\/div> \n","protected":false},"excerpt":{"rendered":"<p>Miami &#8211; Carnival Corporation expandir\u00e1 su presencia en Puerto Rico, al confirmar que entre los a\u00f1os fiscales 2027 y 2028 contar\u00e1 con operaciones de sus marcas Carnival Cruise Line, Princess Cruises y Seabourn Cruise Line en los muelles de cruceros de San Juan. La directora ejecutiva de la Compa\u00f1\u00eda de Turismo de Puerto Rico (CTPR)<\/p>\n","protected":false},"author":2,"featured_media":25019,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-25018","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/posts\/25018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/comments?post=25018"}],"version-history":[{"count":0,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/posts\/25018\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/media\/25019"}],"wp:attachment":[{"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/media?parent=25018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/categories?post=25018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/tags?post=25018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}