{"id":24998,"date":"2026-05-13T07:51:04","date_gmt":"2026-05-13T11:51:04","guid":{"rendered":"https:\/\/aleeknews.com\/4l33k5\/2026\/05\/13\/embajadas-de-iran-utilizaron-el-nacimiento-de-hija-de-karoline-leavitt-para-recordarle-la-muerte-de-ninos-en-escuela-de-minab\/"},"modified":"2026-05-13T07:51:04","modified_gmt":"2026-05-13T11:51:04","slug":"embajadas-de-iran-utilizaron-el-nacimiento-de-hija-de-karoline-leavitt-para-recordarle-la-muerte-de-ninos-en-escuela-de-minab","status":"publish","type":"post","link":"https:\/\/aleeknews.com\/4l33k5\/2026\/05\/13\/embajadas-de-iran-utilizaron-el-nacimiento-de-hija-de-karoline-leavitt-para-recordarle-la-muerte-de-ninos-en-escuela-de-minab\/","title":{"rendered":"Embajadas de Ir\u00e1n utilizaron el nacimiento de hija de Karoline Leavitt para recordarle la muerte de ni\u00f1os en escuela de Minab"},"content":{"rendered":"<div>\n<p>Las embajadas iran\u00edes en Armenia y Sud\u00e1frica publicaron mensajes en sus respectivas cuentas de X felicitando a la secretaria de Prensa de la <a href=\"https:\/\/www.elnuevodia.com\/topicos\/casa-blanca\/\" target=\"_self\" rel title=\"https:\/\/www.elnuevodia.com\/topicos\/casa-blanca\/\"><b>Casa Blanca<\/b><\/a>, <b>Karoline Leavitt<\/b>, por el nacimiento de su hija y <b>record\u00e1ndole la muerte de, al menos, 120 ni\u00f1os luego que un misil, presuntamente de <\/b><a href=\"https:\/\/www.elnuevodia.com\/topicos\/estados-unidos\/\" target=\"_self\" rel title=\"https:\/\/www.elnuevodia.com\/topicos\/estados-unidos\/\"><b>Estados Unidos<\/b><\/a><b>, impact\u00f3 la escuela Shajareh Tayyebeh en Minab<\/b>.<\/p>\n<p>El incidente ocurri\u00f3 el 28 de febrero, durante el primer d\u00eda de ataques de Estados Unidos e <a href=\"https:\/\/www.elnuevodia.com\/topicos\/israel\/\" target=\"_self\" rel title=\"https:\/\/www.elnuevodia.com\/topicos\/israel\/\"><b>Israel<\/b><\/a> contra Ir\u00e1n. Tras el incidente, el presidente <a href=\"https:\/\/www.elnuevodia.com\/topicos\/donald-trump\/\" target=\"_self\" rel title=\"https:\/\/www.elnuevodia.com\/topicos\/donald-trump\/\"><b>Donald Trump<\/b><\/a> sugiri\u00f3 que el misil pudo haber sido de Ir\u00e1n; mientras, el <a href=\"https:\/\/www.elnuevodia.com\/topicos\/departamento-de-defensa\/\" target=\"_self\" rel title=\"https:\/\/www.elnuevodia.com\/topicos\/departamento-de-defensa\/\"><b>Departamento de Defensa<\/b><\/a> mantiene una investigaci\u00f3n sobre lo ocurrido.<\/p>\n<p>En su publicaci\u00f3n, la embajada iran\u00ed en Armenia republic\u00f3 un mensaje de Leavitt y foto anunciando el nacimiento de su hija Viviana y a\u00f1adi\u00f3 que \u201clos ni\u00f1os son inocentes y cari\u00f1osos. Esos 168 ni\u00f1os que tu jefe mat\u00f3 en la escuela en Minab, y que t\u00fa (Leavitt) justificaste, tambi\u00e9n eran ni\u00f1os. Cuando beses a tu hija, piensa en las madres de esos ni\u00f1os\u201d.<\/p>\n<p>Por su parte, la embajada iran\u00ed en Sud\u00e1frica se\u00f1al\u00f3 que \u201ccuando tu hija crezca y lea sobre la historia, se sentir\u00e1 avergonzada de que serviste a uno de los gobiernos m\u00e1s odiados en la historia. Tus manos est\u00e1n manchadas con la sangre de muchos ni\u00f1os inocentes, como los ni\u00f1os de Minab\u201d.<\/p>\n<div data-oembed-type=\"twitter\">\n<blockquote>\n<p lang=\"en\" dir=\"ltr\">Congratulations to you. Children are innocent and lovable. Those 168 children that your boss killed in the school in Minab, and you justified, were also children. When you kiss your baby, think of the mothers of those children. <a href=\"https:\/\/t.co\/uhypZFhRRf\">https:\/\/t.co\/uhypZFhRRf<\/a><\/p>\n<p>\u2014 IRI Embassy in Armenia (@iraninyerevan) <a href=\"https:\/\/twitter.com\/iraninyerevan\/status\/2053139295037227035?ref_src=twsrc%5Etfw\">May 9, 2026<\/a><\/p><\/blockquote>\n<\/div>\n<p>Leavitt, de 28 a\u00f1os, est\u00e1 casada con el empresario Nicholas Riccio, de 60, con quien tiene otro hijo, Niko, nacido en 2024. <\/p>\n<p>Seg\u00fan m\u00faltiples medios, la zona en la que ubicaba la escuela fue impactada por m\u00faltiples misiles. Su techo colaps\u00f3, y un total de 156 civiles murieron, incluyendo 120 ni\u00f1os.<\/p>\n<p>El incidente fue condenado tanto por Ir\u00e1n como por la UNESCO (Organizaci\u00f3n Educacional, Cient\u00edfica y Cultural de las Naciones Unidas) y diversas entidades internacionales de derechos civiles.<\/p>\n<div data-oembed-type=\"twitter\">\n<blockquote>\n<div lang=\"en\" dir=\"ltr\">\n<p>When your child grows up and reads history, she will be ashamed that you served one of the most hated governments in history.<\/p>\n<p>Your hands are stained with the blood of many innocent children, like the children of Minab. <a href=\"https:\/\/t.co\/Mq5TTkZWPP\">https:\/\/t.co\/Mq5TTkZWPP<\/a><\/p>\n<\/div>\n<p>\u2014 Iran Embassy SA (@IraninSA) <a href=\"https:\/\/twitter.com\/IraninSA\/status\/2053252145277792366?ref_src=twsrc%5Etfw\">May 9, 2026<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n\n    <div class=\"xs_social_share_widget xs_share_url after_content \t\tmain_content  wslu-style-1 wslu-share-box-shaped wslu-fill-colored wslu-none wslu-share-horizontal wslu-theme-font-no wslu-main_content\">\n\n\t\t\n        <ul>\n\t\t\t        <\/ul>\n    <\/div> \n","protected":false},"excerpt":{"rendered":"<p>Las embajadas iran\u00edes en Armenia y Sud\u00e1frica publicaron mensajes en sus respectivas cuentas de X felicitando a la secretaria de Prensa de la Casa Blanca , Karoline Leavitt, por el nacimiento de su hija y record\u00e1ndole la muerte de, al menos, 120 ni\u00f1os luego que un misil, presuntamente de Estados Unidos , impact\u00f3 la escuela<\/p>\n","protected":false},"author":2,"featured_media":24999,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-24998","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/posts\/24998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/comments?post=24998"}],"version-history":[{"count":0,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/posts\/24998\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/media\/24999"}],"wp:attachment":[{"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/media?parent=24998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/categories?post=24998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/tags?post=24998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}