{"id":24978,"date":"2026-05-12T10:43:03","date_gmt":"2026-05-12T14:43:03","guid":{"rendered":"https:\/\/aleeknews.com\/4l33k5\/2026\/05\/12\/tengo-asma-ahora-que\/"},"modified":"2026-05-12T10:43:03","modified_gmt":"2026-05-12T14:43:03","slug":"tengo-asma-ahora-que","status":"publish","type":"post","link":"https:\/\/aleeknews.com\/4l33k5\/2026\/05\/12\/tengo-asma-ahora-que\/","title":{"rendered":"Tengo asma, \u00bfahora qu\u00e9?"},"content":{"rendered":"<div>\n<p>El aparato respiratorio est\u00e1 formado por las fosas nasales, la laringe, la tr\u00e1quea y los alv\u00e9olos. La tr\u00e1quea se ramifica en dos bronquios y estos en conductos m\u00e1s peque\u00f1os denominados bronquiolos. <\/p>\n<p>Al final de los bronquiolos se encuentran los alv\u00e9olos, que son unos sacos muy peque\u00f1os en los que se produce el intercambio de ox\u00edgeno y di\u00f3xido de carbono entre el pulm\u00f3n y la sangre durante la respiraci\u00f3n. <\/p>\n<p>De hecho, el ox\u00edgeno que entra con cada inspiraci\u00f3n atraviesa los alv\u00e9olos, pasa a la sangre y llega a los tejidos de todo el cuerpo. El di\u00f3xido de carbono que viene de los tejidos, viaja en la sangre, atraviesa los alv\u00e9olos y se expulsa del cuerpo durante la espiraci\u00f3n.<\/p>\n<p>El asma afecta principalmente a los bronquios y a los bronquiolos. Los especialistas del Hospital Cl\u00ednic de Barcelona explican que, <b>en las personas con asma, la pared de los bronquios se inflama y se hace m\u00e1s gruesa, hay mayor producci\u00f3n de moco, que es viscoso y dif\u00edcil de eliminar, y el m\u00fasculo que rodea las paredes de los bronquios se contrae haciendo que el espacio disponible para que pase el aire sea m\u00e1s peque\u00f1o, lo que dificulta la respiraci\u00f3n<\/b>.<\/p>\n<p>La <a href=\"https:\/\/www.elnuevodia.com\/topicos\/organizacion-mundial-de-la-salud\/\" target=\"_blank\" rel=\"noreferrer\" title=\"https:\/\/www.elnuevodia.com\/topicos\/organizacion-mundial-de-la-salud\/\"><b>Organizaci\u00f3n Mundial de la Salud <\/b><\/a><b>(OMS) <\/b>se\u00f1ala que los s\u00edntomas m\u00e1s habituales del asma son: tos persistente, sobre todo por la noche; sibilancias (pitos) al espirar y, a veces, al inspirar; disnea (dificultad para respirar), en ocasiones incluso en reposo, y opresi\u00f3n en el pecho que no permite respirar profundamente.<\/p>\n<p>Los s\u00edntomas pueden ser distintos seg\u00fan la persona. Cuando se agravan mucho, se produce una crisis asm\u00e1tica. Estas crisis o ataques de asma pueden ser leves, moderadas o graves.<b> En las crisis leves<\/b>, las molestias pueden aparecer con las actividades de la vida diaria, pero no impiden realizarlas. <b>En las moderadas<\/b>, las molestias se intensifican e impiden hacer algunas actividades habituales. Por \u00faltimo, <b>cuando una crisis es grave<\/b>, los s\u00edntomas impiden hablar con normalidad. <\/p>\n<p>Algunas de estas crisis pueden hacer que los labios se pongan azules y, en las peores, se puede perder el conocimiento, detallan los especialistas del Hospital Quir\u00f3n de Madrid. <\/p>\n<p>Cuando se produce una crisis grave, es necesario acudir a los servicios de urgencias. Evitar las crisis es uno de los principales objetivos del tratamiento contra el asma. Aunque la enfermedad no tiene cura, las personas que la padecen pueden mantenerla controlada y hacer una vida normal. <\/p>\n<p>Para ello es necesario cumplir rigurosamente con el tratamiento pautado por el m\u00e9dico. Es fundamental que el paciente aprenda para qu\u00e9 sirve cada uno de los f\u00e1rmacos y c\u00f3mo usarlos de la manera correcta.<\/p>\n<p>\u201cLa medicaci\u00f3n de la que disponemos para el asma es muy eficaz y el asm\u00e1tico puede llegar a estar sin s\u00edntomas, a controlarse, evitar las crisis y la p\u00e9rdida de funci\u00f3n respiratoria\u201d, se\u00f1alan los facultativos del Servicio de Neumolog\u00eda del Hospital Quir\u00f3n de Madrid.<\/p>\n<div>\n<p><b>1 \/ 10 | <\/b><span> \u00bfTienes catarro o acidez? Aqu\u00ed 10 remedios caseros m\u00e1s usados. C\u00farcuma: Es una de las especias m\u00e1s populares para tratar el dolor. Est\u00e1 comprobado que los curcuminoides en dosis adecuadas, generan mayor biodisponibilidad del col\u00e1geno a nivel articular, o sea que mejoran su llegada a todas las articulaciones. Si al consumirlo se le agrega pimienta negra, se genera un efecto a\u00fan m\u00e1s potente. Si bien los m\u00e9dicos suelen recomendar una dosis de 500 miligramos de c\u00farcuma dos veces al d\u00eda con alimentos, la dosis adecuada para cada persona puede variar seg\u00fan su estado general de salud y la indicaci\u00f3n profesional.<\/span><i> &#8211; Shutterstock<\/i><\/p>\n<\/div>\n<p><h4><b>Antiinflamatorios o broncodilatadores<\/b><\/h4>\n<\/p>\n<p>Los f\u00e1rmacos empleados para tratar el asma pueden ser antiinflamatorios o broncodilatadores. Los antiinflamatorios \u201celiminan o mitigan la inflamaci\u00f3n de los bronquios, que es la causa del asma. Al desinflamar los bronquios, desaparecen los s\u00edntomas y aumenta la capacidad pulmonar, se evita que la inflamaci\u00f3n vaya a m\u00e1s y se generen crisis asm\u00e1ticas\u201d, detallan. <\/p>\n<p>Los m\u00e1s utilizados son los corticoides inhalados y los antagonistas de los receptores de los leucotrienos, que se toman por v\u00eda oral. Estos \u00faltimos bloquean la acci\u00f3n de los leucotrienos, que son sustancias inflamatorias generadas por el sistema inmune, de manera que reducen la inflamaci\u00f3n y el moco en las v\u00edas respiratorias.<\/p>\n<p>Por su parte, <b>los medicamentos broncodilatadores act\u00faan sobre el m\u00fasculo de los bronquios, dilat\u00e1ndolo y permitiendo que el aire pase mejor.<\/b> <\/p>\n<p>Los broncodilatadores m\u00e1s utilizados para el tratamiento del asma son: los agonistas beta-2-adren\u00e9rgicos y los anticolin\u00e9rgicos.Los agonistas beta-2-adren\u00e9rgicos se administran por v\u00eda inhalada. Los hay de dos tipos: de acci\u00f3n corta (SABA, por sus siglas en ingl\u00e9s) y de acci\u00f3n prolongada (LABA). Los de acci\u00f3n corta se utilizan como medicaci\u00f3n de rescate, pues alivian s\u00edntomas agudos r\u00e1pidamente. <\/p>\n<p>De hecho, tardan ente 2 y 5 minutos en producir la dilataci\u00f3n de los bronquios y su efecto desaparece en pocas horas. En cambio, los de acci\u00f3n prolongada act\u00faan m\u00e1s lentamente, pero la broncodilataci\u00f3n dura de 12 a 24 horas. Se usan a diario, como medicaci\u00f3n de mantenimiento, en combinaci\u00f3n con los corticoides inhalados. <\/p>\n<p>Otros f\u00e1rmacos broncodilatadores son los anticolin\u00e9rgicos. Tambi\u00e9n se administran por v\u00eda inhalada. \u201cLos hay de inicio r\u00e1pido y cuya acci\u00f3n dura entre 4 y 6 horas. Se pueden utilizar de rescate como alternativa a los agonistas beta-2-adren\u00e9rgicos de acci\u00f3n corta. Y los hay de acci\u00f3n 24 horas que se emplean en combinaci\u00f3n con los beta-2-adren\u00e9rgicos de acci\u00f3n prolongada y los corticoides como tratamiento de mantenimiento\u201d, detallan los especialistas del Hospital Quir\u00f3n de Madrid.<\/p>\n<p>La mayor\u00eda de los tratamientos para el asma se administran de forma inhalada, por lo que es fundamental que la t\u00e9cnica inhalatoria sea correcta para que el medicamento llegue a la zona en la que tiene que actuar. De lo contrario, no llegar\u00eda suficiente medicaci\u00f3n y no se lograr\u00eda el efecto deseado. <\/p>\n<p><b>\u201cEn general, existen dos grandes grupos de inhaladores: los de cartuchos presurizados y los de polvo seco. Dentro de ellos hay diferentes tipos de dispositivos. <\/b>El paciente y el m\u00e9dico deben encontrar la opci\u00f3n que mejor se adapte al enfermo y asegurarse que realiza la t\u00e9cnica inhalatoria correctamente\u201d, destacan los neum\u00f3logos del Hospital Cl\u00ednic de Barcelona.<\/p>\n<p>Adem\u00e1s de cumplir con el tratamiento pautado por el m\u00e9dico, las personas con asma deben evitar ciertos factores que pueden desencadenar los s\u00edntomas de la enfermedad. <\/p>\n<p>Los m\u00e1s habituales son: polen, \u00e1caros del polvo, caspa de animales, humo de tabaco, contaminaci\u00f3n del aire, productos qu\u00edmicos o infecciones respiratorias.Si la persona asm\u00e1tica evita los desencadenantes, conoce su medicaci\u00f3n y sabe cu\u00e1ndo y c\u00f3mo tomarla y, adem\u00e1s, tiene un estilo de vida saludable, puede mantener la enfermedad controlada y llevar una vida normal.<\/p>\n<\/div>\n\n    <div class=\"xs_social_share_widget xs_share_url after_content \t\tmain_content  wslu-style-1 wslu-share-box-shaped wslu-fill-colored wslu-none wslu-share-horizontal wslu-theme-font-no wslu-main_content\">\n\n\t\t\n        <ul>\n\t\t\t        <\/ul>\n    <\/div> \n","protected":false},"excerpt":{"rendered":"<p>El aparato respiratorio est\u00e1 formado por las fosas nasales, la laringe, la tr\u00e1quea y los alv\u00e9olos. La tr\u00e1quea se ramifica en dos bronquios y estos en conductos m\u00e1s peque\u00f1os denominados bronquiolos. Al final de los bronquiolos se encuentran los alv\u00e9olos, que son unos sacos muy peque\u00f1os en los que se produce el intercambio de ox\u00edgeno<\/p>\n","protected":false},"author":2,"featured_media":24979,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[38],"tags":[],"class_list":["post-24978","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estilo-de-vida"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/posts\/24978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/comments?post=24978"}],"version-history":[{"count":0,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/posts\/24978\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/media\/24979"}],"wp:attachment":[{"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/media?parent=24978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/categories?post=24978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/tags?post=24978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}