{"id":24946,"date":"2026-05-12T07:42:43","date_gmt":"2026-05-12T11:42:43","guid":{"rendered":"https:\/\/aleeknews.com\/4l33k5\/2026\/05\/12\/revelan-nueva-lista-de-paises-que-han-confirmado-casos-de-hantavirus-tras-brote-en-crucero-2\/"},"modified":"2026-05-12T07:42:43","modified_gmt":"2026-05-12T11:42:43","slug":"revelan-nueva-lista-de-paises-que-han-confirmado-casos-de-hantavirus-tras-brote-en-crucero-2","status":"publish","type":"post","link":"https:\/\/aleeknews.com\/4l33k5\/2026\/05\/12\/revelan-nueva-lista-de-paises-que-han-confirmado-casos-de-hantavirus-tras-brote-en-crucero-2\/","title":{"rendered":"Revelan nueva lista de pa\u00edses que han confirmado casos de hantavirus tras brote en crucero"},"content":{"rendered":"<div>\n<p>El brote de <a href=\"https:\/\/www.elnuevodia.com\/topicos\/hantavirus\/\" target=\"_self\" rel title=\"https:\/\/www.elnuevodia.com\/topicos\/hantavirus\/\">hantavirus<\/a> relacionado con el crucero MV Hondius sigue sumando nuevos casos confirmados en distintos pa\u00edses. <b>Este lunes 11 de mayo, autoridades sanitarias de <\/b><a href=\"https:\/\/www.elnuevodia.com\/topicos\/francia\/\" target=\"_self\" rel title=\"https:\/\/www.elnuevodia.com\/topicos\/francia\/\"><b>Francia<\/b><\/a><b> y <\/b><a href=\"https:\/\/www.elnuevodia.com\/noticias\/estados-unidos\/\" target=\"_self\" rel title=\"https:\/\/www.elnuevodia.com\/noticias\/estados-unidos\/\"><b>Estados Unidos<\/b><\/a><b> reportaron positivos entre pasajeros evacuados desde Tenerife, Espa\u00f1a<\/b>, mientras contin\u00faa la operaci\u00f3n internacional de repatriaci\u00f3n de ocupantes del barco, que permanece bajo vigilancia sanitaria tras la muerte de tres pasajeros.<\/p>\n<p>El Gobierno espa\u00f1ol confirm\u00f3 que se trata de un ciudadano estadounidense y una pasajera francesa evacuados el domingo desde el crucero que dieron positivo por hantavirus. <\/p>\n<p><b>\u201cSe han aplicado todas las medidas preventivas y de control de transmisi\u00f3n\u201d<\/b>, asegur\u00f3 el Ministerio de Salud espa\u00f1ol en un comunicado, conocido por la agencia AFP, en el que indic\u00f3 adem\u00e1s que \u201ctodas las medidas adoptadas desde el inicio han tenido como objetivo cortar las posibles cadenas de transmisi\u00f3n\u201d.<\/p>\n<p>La emergencia sanitaria se origin\u00f3 a bordo del MV Hondius, un crucero de bandera neerlandesa operado por Oceanwide Expeditions, que hab\u00eda partido el 1 de abril desde Ushuaia, Argentina, para una traves\u00eda por el Atl\u00e1ntico. En el barco viajaban cerca de 150 personas entre pasajeros y tripulaci\u00f3n de m\u00e1s de 20 nacionalidades.<\/p>\n<div>\n<p><b>1 \/ 17 | <\/b><span> En aviones del gobierno, militares y ambulancias: as\u00ed repatrian a pasajeros de crucero con hantavirus. Un pasajero sube a un avi\u00f3n del gobierno franc\u00e9s tras desembarcar del crucero MV Hondius, afectado por el hantavirus, en el aeropuerto de Tenerife.<\/span><i> &#8211; Arturo Rodriguez<\/i><\/p>\n<\/div>\n<p>Hasta ahora, las autoridades han confirmado la muerte de tres pasajeros: un matrimonio neerland\u00e9s y una mujer alemana. Adem\u00e1s, varios pasajeros y miembros de la tripulaci\u00f3n presentaron s\u00edntomas respiratorios compatibles con hantavirus, mientras otros fueron considerados contactos estrechos y puestos en cuarentena. <\/p>\n<p>La esposa de la primera v\u00edctima, una mujer de 69 a\u00f1os, muri\u00f3 tras ser trasladada a Pa\u00edses Bajos para recibir atenci\u00f3n. Los otros casos murieron en el barco. <\/p>\n<p><b>El Departamento de Salud de Estados Unidos inform\u00f3 que uno de los ciudadanos estadounidenses evacuados este domingo 10 de mayo \u201cdio positivo leve en la prueba PCR\u201d al virus Andes, la variante asociada al brote. <\/b><\/p>\n<p>La entidad indic\u00f3 adem\u00e1s que otro pasajero presenta s\u00edntomas leves y que ambos viajaron en \u201clos compartimientos de confinamiento biol\u00f3gico del avi\u00f3n\u201d durante la repatriaci\u00f3n hacia un centro especializado en Nebraska.<\/p>\n<p>Por su parte, la ministra de Salud de Francia, St\u00e9phanie Rist, confirm\u00f3 que una pasajera francesa empeor\u00f3 tras ser evacuada. <b>\u201cEl estado de salud de una mujer \u2018lamentablemente se deterior\u00f3 esta noche\u2019 y las \u2018pruebas dieron positivo\u2019\u201d, declar\u00f3 la funcionaria. Los cinco ciudadanos franceses repatriados permanecen aislados en Par\u00eds<\/b>.<\/p>\n<p>Seg\u00fan explic\u00f3 la ministra francesa, todos \u201cest\u00e1n hospitalizados en habitaciones con flujos de aire que permiten evitar el contagio\u201d. Adem\u00e1s, indic\u00f3 que se identificaron 22 contactos relacionados con el caso: ocho personas que viajaron en un vuelo entre Santa Elena y Johannesburgo y otras 14 que estuvieron en el trayecto Johannesburgo-\u00c1msterdam.<\/p>\n<p>La paciente francesa habr\u00eda comenzado a presentar s\u00edntomas durante el vuelo de evacuaci\u00f3n. El Ministerio de Salud espa\u00f1ol sostuvo que \u201cla paciente francesa comenz\u00f3 a encontrarse mal durante el vuelo y no mientras se encontraba en el buque\u201d.<\/p>\n<p>Mientras tanto, <b>Alemania tambi\u00e9n activ\u00f3 protocolos sanitarios. Cuatro pasajeros alemanes evacuados del crucero fueron trasladados a la Cl\u00ednica Universitaria de Fr\u00e1ncfort, donde permanecen aislados.<\/b> El portavoz del Ministerio de Sanidad alem\u00e1n, Martin Els\u00e4sser, confirm\u00f3 que las personas \u201chan tenido contacto (con el virus)\u201d y posteriormente ser\u00edan trasladadas a sus regiones de origen bajo coordinaci\u00f3n de autoridades regionales.<\/p>\n<p><b>Irlanda tambi\u00e9n mantiene vigilancia sobre dos pasajeras repatriadas a Dubl\u00edn. <\/b>Las autoridades sanitarias se\u00f1alaron que ambas se encuentran \u201ccon buen \u00e1nimo y gozan de buena salud\u201d, aunque permanecer\u00e1n aisladas durante el periodo recomendado por la Organizaci\u00f3n Mundial de la Salud (OMS) y el Centro Europeo para la Prevenci\u00f3n y el Control de las Enfermedades.<\/p>\n<p>La expansi\u00f3n de casos vinculados al crucero se suma al reciente reporte conocido en Israel. <b>Seg\u00fan inform\u00f3 The Jerusalem Post, el primer caso de hantavirus fue diagnosticado en ese pa\u00eds en la \u00faltima semana<\/b>. <\/p>\n<p>El paciente, de acuerdo con la publicaci\u00f3n de ese 10 de mayo, habr\u00eda contra\u00eddo la enfermedad durante una estancia en Europa del Este y acudi\u00f3 a atenci\u00f3n m\u00e9dica tras desarrollar s\u00edntomas relacionados con el virus.<\/p>\n<p>De igual forma, seg\u00fan recogi\u00f3 BBC, otro ciudadano suizo que desembarc\u00f3 de un crucero en Santa Elena ya dio positivo a la cepa Andes del hantavirus. Las autoridades sanitarias suizas y la OMS, citadas en el informe, se\u00f1alaron que el hombre present\u00f3 s\u00edntomas y se someti\u00f3 a pruebas en Z\u00farich, donde est\u00e1 recibiendo atenci\u00f3n m\u00e9dica.<\/p>\n<p><b>La <\/b><a href=\"https:\/\/www.elnuevodia.com\/topicos\/oms\/\" target=\"_self\" rel title=\"https:\/\/www.elnuevodia.com\/topicos\/oms\/\"><b>OMS<\/b><\/a><b> ha insistido en que el riesgo global contin\u00faa siendo bajo. El director del organismo, Tedros Adhanom Ghebreyesus, quien estuvo presente en Tenerife durante parte de la operaci\u00f3n de evacuaci\u00f3n, reiter\u00f3 que \u201cel riesgo actual para la salud p\u00fablica sigue siendo bajo\u201d.<\/b><\/p>\n<p>Las autoridades sanitarias han se\u00f1alado que la cepa identificada corresponde al virus Andes, una variante presente en Am\u00e9rica Latina y que, a diferencia de otros hantavirus, s\u00ed puede transmitirse entre personas en contactos estrechos. El periodo de incubaci\u00f3n puede extenderse hasta seis semanas.<\/p>\n<p>El <b>Ministerio de Salud de Argentina<\/b> inform\u00f3 el pasado 6 de mayo que \u201cse confirm\u00f3 la existencia de 8 casos entre los pasajeros y la tripulaci\u00f3n del buque MV Hondius y 3 de ellos fallecieron\u201d. Adem\u00e1s, indic\u00f3 que <b>\u201cla variante corresponde a la cepa Andes, la cual solo presenta antecedentes de circulaci\u00f3n en Chubut, R\u00edo Negro y Neuqu\u00e9n y en el sur de Chile\u201d<\/b>.<\/p>\n<p>Entre los casos sospechosos, BBC agreg\u00f3 a tres ciudadanos brit\u00e1nicos, quienes desembarcaron del MV Hondius en Santa Elena el 24 de abril, antes de que se notificara el primer caso confirmado de hantavirus el 4 de mayo.<\/p>\n<p>De acuerdo con el reporte, un paciente se encuentra en la isla Trist\u00e1n de Acu\u00f1a. Sobre los confirmados, se cuentan a dos hombres brit\u00e1nicos, uno identificado como Martin Anstee, un expolic\u00eda jubilado de 56 a\u00f1os que permanece en Pa\u00edses Bajos, mientras el otro est\u00e1 hospitalizado en cuidados intensivos despu\u00e9s de haber sido trasladado por v\u00eda a\u00e9rea a Sud\u00e1frica el mes pasado.<\/p>\n<p>Por lo pronto, las autoridades argentinas indicaron que el pa\u00eds sudamericano avanza en la reconstrucci\u00f3n del itinerario del matrimonio neerland\u00e9s considerado caso \u00edndice. El informe difundido revela que la pareja arrib\u00f3 a Argentina el 27 de noviembre del a\u00f1o pasado y recorri\u00f3 varias zonas del pa\u00eds y Chile antes de embarcar en Ushuaia el 1 de abril.<\/p>\n<p><b>\u201cEl itinerario incluye tambi\u00e9n el ingreso a la provincia de Neuqu\u00e9n el 31 de enero y una nueva visita a Chile 12 d\u00edas m\u00e1s tarde\u201d, detall\u00f3 el Ministerio de Salud argentino.<\/b> Posteriormente, la pareja viaj\u00f3 hacia Mendoza, Misiones, Uruguay y finalmente regres\u00f3 a Argentina antes de abordar el crucero.<\/p>\n<p>Argentina asegur\u00f3 adem\u00e1s que \u201chasta el momento, no se identificaron casos asociados en el pa\u00eds\u201d, aunque t\u00e9cnicos del Instituto Malbr\u00e1n viajar\u00e1n a Ushuaia para realizar capturas y an\u00e1lisis de roedores en \u00e1reas vinculadas al recorrido de los primeros pacientes.<\/p>\n<p>El MV Hondius permanece actualmente en Tenerife tras la evacuaci\u00f3n de decenas de pasajeros y tripulantes. Espa\u00f1a organiz\u00f3 vuelos de repatriaci\u00f3n hacia distintos pa\u00edses bajo estrictas medidas de seguridad sanitaria. Seg\u00fan las autoridades, los \u00faltimos vuelos previstos saldr\u00e1n hacia Australia y Pa\u00edses Bajos antes de que el barco contin\u00fae rumbo a territorio neerland\u00e9s con una tripulaci\u00f3n reducida.<\/p>\n<p><h4><b>Listado de pa\u00edses que han confirmado casos o aislamientos vinculados al brote del MV Hondius:<\/b><\/h4>\n<\/p>\n<p>&#8211; Espa\u00f1a<\/p>\n<p>&#8211; Estados Unidos<\/p>\n<p>&#8211; Francia<\/p>\n<p>&#8211; Alemania<\/p>\n<p>&#8211; Irlanda<\/p>\n<p>&#8211; Pa\u00edses Bajos<\/p>\n<p>&#8211; Inglaterra<\/p>\n<p>&#8211; Sud\u00e1frica<\/p>\n<p>&#8211; Israel<\/p>\n<p><b>&#8212;<\/b><\/p>\n<p><i>*Con informaci\u00f3n de EFE y AFP<\/i><\/p>\n<\/div>\n\n    <div class=\"xs_social_share_widget xs_share_url after_content \t\tmain_content  wslu-style-1 wslu-share-box-shaped wslu-fill-colored wslu-none wslu-share-horizontal wslu-theme-font-no wslu-main_content\">\n\n\t\t\n        <ul>\n\t\t\t        <\/ul>\n    <\/div> \n","protected":false},"excerpt":{"rendered":"<p>El brote de hantavirus relacionado con el crucero MV Hondius sigue sumando nuevos casos confirmados en distintos pa\u00edses. Este lunes 11 de mayo, autoridades sanitarias de Francia y Estados Unidos reportaron positivos entre pasajeros evacuados desde Tenerife, Espa\u00f1a, mientras contin\u00faa la operaci\u00f3n internacional de repatriaci\u00f3n de ocupantes del barco, que permanece bajo vigilancia sanitaria tras<\/p>\n","protected":false},"author":2,"featured_media":24945,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-24946","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/posts\/24946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/comments?post=24946"}],"version-history":[{"count":0,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/posts\/24946\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/media\/24945"}],"wp:attachment":[{"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/media?parent=24946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/categories?post=24946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/tags?post=24946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}