{"id":15715,"date":"2025-11-22T14:45:48","date_gmt":"2025-11-22T13:45:48","guid":{"rendered":"https:\/\/aleeknews.com\/4l33k5\/2025\/11\/22\/avanza-la-construccion-de-nuevas-egidas\/"},"modified":"2025-11-22T14:45:48","modified_gmt":"2025-11-22T13:45:48","slug":"avanza-la-construccion-de-nuevas-egidas","status":"publish","type":"post","link":"https:\/\/aleeknews.com\/4l33k5\/2025\/11\/22\/avanza-la-construccion-de-nuevas-egidas\/","title":{"rendered":"Avanza la construcci\u00f3n de nuevas \u00e9gidas"},"content":{"rendered":"<div>\n<div data-testid=\"global-header-test\" data-fusion-lazy-id=\"f0f5G41E11Y61Ck\">\n<hr>\n<p><span>Bolsa de valores <b>01:32 PM<\/b><\/span><\/p>\n<\/div>\n<div>\n<div data-fusion-lazy-id=\"f0f9tfiOw0362nv\">\n<div class>\n<p><a href=\"https:\/\/thetrustproject.org\/\"><img decoding=\"async\" src=\"https:\/\/www.elnuevodia.com\/pf\/resources\/v2\/icons\/trust-icon.svg?d=217\"><\/a><\/p>\n<div>\n<p>Se adhiere a los criterios de The Trust Project<\/p>\n<\/div>\n<\/div>\n<div>\n<h2>Desarrolladores erigen y remozan complejos de vivienda subsidiada, pero crece el n\u00famero de adultos mayores que encara retos para acceder a una vivienda asequible <\/h2>\n<div>\n<p>1 de noviembre de 2025 &#8211; 11:10 PM<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div data-fusion-lazy-id=\"f0f8wxHIPTYNet\">\n<div><picture><source media=\"(max-width: 375px)\" ><source media=\"(max-width: 767px)\" ><source media=\"(max-width: 1023px)\" ><source ><\/picture><figcaption>\u00c9gida 837, en la zona urbana de Guaynabo, se erige con una inversi\u00f3n de $93 millones. Es uno de los 8 proyectos de vivienda de alquiler subsidiado para mayores de 62 a\u00f1os que se adelantan con cr\u00e9ditos y fondos federales.  <span>(Carlos Rivera Giusti)<\/span><\/figcaption><\/div>\n<div>\n<p><img decoding=\"async\" alt=\"Sharon Minelli P\u00e9rez\" src=\"https:\/\/www.elnuevodia.com\/resizer\/v2\/https%3A%2F%2Fs3.amazonaws.com%2Farc-authors%2Fgfrmedia%2F8e50d93e-0a9f-40ca-bda3-a3fc69f705fa.png?auth=ca40016ef4aff5e1315ee2650a1e5df14a4ccd8bb305ec40f5454f7dd1dccc4a&#038;quality=75&#038;smart=true&#038;width=170&#038;height=147\"><\/p>\n<\/div>\n<div>\n<p>Con una poblaci\u00f3n m\u00e1s envejecida que nunca, Puerto Rico destina unos $1,800 millones en fondos federales para construir y rehabilitar una nueva generaci\u00f3n de edificios de alquiler subsidiado, que incluyen ocho \u00e9gidas para adultos mayores con ingresos bajos.<\/p>\n<\/div>\n<\/div>\n<section>\n<header><span>Popular en la Comunidad<\/span><\/header>\n<\/section>\n<\/div>\n<\/div>\n\n    <div class=\"xs_social_share_widget xs_share_url after_content \t\tmain_content  wslu-style-1 wslu-share-box-shaped wslu-fill-colored wslu-none wslu-share-horizontal wslu-theme-font-no wslu-main_content\">\n\n\t\t\n        <ul>\n\t\t\t        <\/ul>\n    <\/div> \n","protected":false},"excerpt":{"rendered":"<p>Bolsa de valores 01:32 PM Se adhiere a los criterios de The Trust Project Desarrolladores erigen y remozan complejos de vivienda subsidiada, pero crece el n\u00famero de adultos mayores que encara retos para acceder a una vivienda asequible 1 de noviembre de 2025 &#8211; 11:10 PM \u00c9gida 837, en la zona urbana de Guaynabo, se<\/p>\n","protected":false},"author":2,"featured_media":15716,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-15715","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/posts\/15715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/comments?post=15715"}],"version-history":[{"count":0,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/posts\/15715\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/media\/15716"}],"wp:attachment":[{"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/media?parent=15715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/categories?post=15715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/tags?post=15715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}