{"id":14686,"date":"2025-11-04T07:44:44","date_gmt":"2025-11-04T06:44:44","guid":{"rendered":"https:\/\/aleeknews.com\/4l33k5\/2025\/11\/04\/opinion-puerto-rico-y-jamaica-islas-en-paralelo\/"},"modified":"2025-11-04T07:44:44","modified_gmt":"2025-11-04T06:44:44","slug":"opinion-puerto-rico-y-jamaica-islas-en-paralelo","status":"publish","type":"post","link":"https:\/\/aleeknews.com\/4l33k5\/2025\/11\/04\/opinion-puerto-rico-y-jamaica-islas-en-paralelo\/","title":{"rendered":"Opini\u00f3n | Puerto Rico y Jamaica: \u00bfislas en paralelo?"},"content":{"rendered":"<div>\n<div data-fusion-lazy-id=\"f0fW0AnQWGof2kd\">\n<div class>\n<p>Opini\u00f3n<\/p>\n<div>\n<p>Explica ideas y extrae conclusiones basadas en la interpretaci\u00f3n de hechos y datos.<\/p>\n<\/div>\n<\/div>\n<div>\n<h2>En Jamaica manda el Fondo Monetario Internacional, aqu\u00ed la Junta de Control Fiscal. All\u00e1 vienen tom\u00e1ndose la medicina amarga del FMI desde 2013 con relativo \u00e9xito. Aqu\u00ed todav\u00eda no se ve la luz al final del t\u00fanel, escribe Rafael Cox Alomar<\/h2>\n<div>\n<p>4 de noviembre de 2025 &#8211; 11:10 PM<\/p>\n<\/div>\n<\/div>\n<div>\n<p>Las opiniones expresadas en este art\u00edculo son \u00fanicamente del autor y no reflejan las opiniones y creencias de El Nuevo D\u00eda o sus afiliados.<\/p>\n<\/div>\n<\/div>\n<div data-fusion-lazy-id=\"f0f0LDhCGuW61Yy\">\n<div><picture><source media=\"(max-width: 375px)\" ><source media=\"(max-width: 767px)\" ><source media=\"(max-width: 1023px)\" ><source ><\/picture><figcaption>Aqu\u00ed el gobierno todav\u00eda espera por FEMA (a nueve a\u00f1os de Mar\u00eda), all\u00e1 est\u00e1n a punto de cobrar la p\u00f3liza de cat\u00e1strofe (catastrophe bond) que las autoridades jamaiquinas (previniendo el futuro) ya hab\u00edan adquirido del Banco Mundial, escribe Rafael Cox Alomar. <span>(RICARDO MAKYN)<\/span><\/figcaption><\/div>\n<div>\n<p>Arras\u00f3 con Jamaica. No dej\u00f3 t\u00edtere con cabeza. Con vientos de 185 millas por hora, Melissa es el hurac\u00e1n m\u00e1s devastador que jam\u00e1s pas\u00f3 por la vecina isla naci\u00f3n. <\/p>\n<\/div>\n<\/div>\n<div>\n<p><b>Gu\u00edas de Opini\u00f3n<\/b><\/p>\n<p>Las columnas deben enviarse a Gerardo Cordero: gerardo.cordero@gfrmedia.com. Las columnas tienen que ser de 300, 400 o 500 palabras. Al enviarnos su columna, el escritor concede a GFR Media una licencia exclusiva, perpetua, irrevocable, sublicenciable, mundial y libre de regal\u00edas para reproducir, copiar, distribuir, publicar, exhibir, preparar obras derivadas, traducir, sindicar, incluir en compilaciones u obras colectivas, y de cualquier otro modo de forma general utilizar su columna (en todo o en parte), sin reserva ni limitaci\u00f3n alguna, en cualquier medio (incluyendo pero sin limitarse, a las versiones impresas o digitales o en los sitios web o aplicaciones m\u00f3vil del peri\u00f3dico El Nuevo D\u00eda), forma, tecnolog\u00eda o m\u00e9todo conocido en el presente o que sea conocido, desarrollado o descubierto en el futuro. El autor acepta que GFR Media, LLC, podr\u00eda cobrar a los suscriptores las versiones digitales, sitios web o aplicaciones m\u00f3viles de GFR Media por el acceso a la columna. <\/p>\n<\/div>\n<section>\n<header><span>Popular en la Comunidad<\/span><\/header>\n<\/section>\n<\/div>\n\n    <div class=\"xs_social_share_widget xs_share_url after_content \t\tmain_content  wslu-style-1 wslu-share-box-shaped wslu-fill-colored wslu-none wslu-share-horizontal wslu-theme-font-no wslu-main_content\">\n\n\t\t\n        <ul>\n\t\t\t        <\/ul>\n    <\/div> \n","protected":false},"excerpt":{"rendered":"<p>Opini\u00f3n Explica ideas y extrae conclusiones basadas en la interpretaci\u00f3n de hechos y datos. En Jamaica manda el Fondo Monetario Internacional, aqu\u00ed la Junta de Control Fiscal. All\u00e1 vienen tom\u00e1ndose la medicina amarga del FMI desde 2013 con relativo \u00e9xito. Aqu\u00ed todav\u00eda no se ve la luz al final del t\u00fanel, escribe Rafael Cox Alomar<\/p>\n","protected":false},"author":2,"featured_media":14687,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[30],"tags":[],"class_list":["post-14686","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opinion"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/posts\/14686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/comments?post=14686"}],"version-history":[{"count":0,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/posts\/14686\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/media\/14687"}],"wp:attachment":[{"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/media?parent=14686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/categories?post=14686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aleeknews.com\/4l33k5\/wp-json\/wp\/v2\/tags?post=14686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}